{"id":795,"date":"2026-08-25T14:21:40","date_gmt":"2026-08-25T14:21:40","guid":{"rendered":"https:\/\/e-fouche.fr\/?post_type=project&#038;p=795"},"modified":"2026-08-26T15:50:31","modified_gmt":"2026-08-26T15:50:31","slug":"lussac","status":"publish","type":"project","link":"https:\/\/e-fouche.fr\/index.php\/project\/lussac\/","title":{"rendered":"Lussac"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; background_enable_image=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb1105px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb|-175px||536px||\u00a0\u00bb custom_padding=\u00a0\u00bb||22px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbDOJO\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb background_enable_image=\u00a0\u00bboff\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row column_structure=\u00a0\u00bb2_5,3_5&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb1105px\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb custom_margin=\u00a0\u00bb|-175px||536px||\u00a0\u00bb custom_padding=\u00a0\u00bb||53px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb2_5&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bbrgba(255,255,255,0.85)\u00a0\u00bb width=\u00a0\u00bb91.8%\u00a0\u00bb custom_padding=\u00a0\u00bb|5px|30px|9px||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"color: #808080;\"><b>Ma\u00eetre d\u2019Ouvrage : <\/b><\/span><\/p>\n<p><span style=\"color: #808080;\">Commune de LUSSAC <span style=\"font-size: 14px;\">(33670)<\/span><\/span><\/p>\n<p><span style=\"color: #808080;\"><b>Contenu de la mission :<\/b><\/span><\/p>\n<p><span style=\"color: #808080;\">Extension Salle de DOJO dans le pr\u00e9au ecistant , Yoga et bureau<br \/><\/span><\/p>\n<p><span style=\"color: #808080;\"><b>Surface cr\u00e9e : <\/b>376m\u00b2<\/span>\u00a0<\/p>\n<p><span style=\"color: #808080;\"><b>Montant des travaux : <\/b>376 K\u20ac HT<\/span><\/p>\n<p><span style=\"color: #808080;\"><b>Livraison : <\/b>Avril 2027 (PRO en cours)<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bbrgba(255,255,255,0.85)\u00a0\u00bb background_color=\u00a0\u00bb#000000&Prime; width=\u00a0\u00bb91.8%\u00a0\u00bb custom_margin=\u00a0\u00bb19px|||||\u00a0\u00bb custom_padding=\u00a0\u00bb|5px|0px|9px||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2><span style=\"color: #ffffff;\"><\/span><\/h2>\n<h2><span style=\"color: #ffffff;\">Particularit\u00e9 du projet\u00a0<\/span><\/h2>\n<ul>\n<li>Structure et toiture conserv\u00e9s<\/li>\n<li>Construction bas carbone en bois et b\u00e9ton dechanvre, enduits terre<\/li>\n<li>Sol sportif<\/li>\n<li>R\u00e9gulation hydrothermique optimis\u00e9e<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_text_color=\u00a0\u00bbrgba(255,255,255,0.85)\u00a0\u00bb width=\u00a0\u00bb91.8%\u00a0\u00bb custom_margin=\u00a0\u00bb35px|||||\u00a0\u00bb custom_padding=\u00a0\u00bb|5px|30px|9px||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><span style=\"color: #808080;\">La mission initiale port\u00e9 sur l\u2019implantation d\u2019un DOJO dans l\u2019ancien pr\u00e9au du coll\u00e8ge de Lussac. Le projet a ensuite \u00e9volu\u00e9 vers l\u2019utilisation pluridisciplinaire, adapt\u00e9 \u00e0 l\u2019\u00e9volution des pratiques des Arts Martiaux et \u00e0 une meilleure rentabilit\u00e9. Le niveau mezzanine, accueillera ainsi une salle de yoga\/gymnastique, bureau, rangements.<\/span><\/p>\n<p><span style=\"color: #808080;\">Inspir\u00e9 de l\u2019esth\u00e9tique japonaise, le projet allie des formes \u00e9pur\u00e9es, jeux de lumi\u00e8re et contrastes lignes structur\u00e9es et courbes, contribuant \u00e0 une exp\u00e9rience \u00e0 la fois physique et spirituelle, fid\u00e8le \u00e0 l\u2019esprit du Judo. <\/span><br \/><span style=\"color: #808080;\">L\u2019extension sera r\u00e9alis\u00e9 en structure ossature bois, remplissage b\u00e9ton de chanvre et bardage \u00e0 claire voie. Des bandeaux vitr\u00e9s en partie haute et des brise-soleil inspir\u00e9s de la g\u00e9om\u00e9trie japonaise assureront confort et luminosit\u00e9.<\/span><\/p>\n<p><span style=\"color: #808080;\">La salle principale conservera son volume existant avec une partie de la charpente apparente. Le plafond sera isol\u00e9 thermiquement et phoniquement. <\/span><br \/><span style=\"color: #808080;\">Un escalier en bois ajour\u00e9 permettra l\u2019acc\u00e8s \u00e0 l\u2019\u00e9tage sans perturber les activit\u00e9s, gr\u00e2ce \u00e0 une claustra faisant office de garde-corps et reprenant les motifs des brise-soleil. <\/span><br \/><span style=\"color: #808080;\">Le projet s\u2019inscrit dans une d\u00e9marche environnementale gr\u00e2ce \u00e0 l\u2019utilisation du bois, du b\u00e9ton de chanvre et d\u2019enduits terre, limitant l\u2019empreinte carbone et am\u00e9liorant les performances thermiques. L\u2019utilisation du b\u00e9ton reste li\u00e9e aux fondations.<\/span><\/p>\n<p><span style=\"color: #808080;\">Les appareillages sont limit\u00e9s aux besoins essentiels, ventilation double-flux et chauffage sur un r\u00e9seau de radiateur, sans climatisation. C\u2019est la r\u00e9gulation hygrothermique du b\u00e9ton de chanvre et l\u2019inertie du b\u00e9ton qui r\u00e9pondra aux p\u00e9riodes estivales.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_5&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb transform_translate_linked=\u00a0\u00bboff\u00a0\u00bb transform_origin=\u00a0\u00bb0%|50%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/e-fouche.fr\/wp-content\/uploads\/2026\/02\/LU_Inser_3-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbLU_Inser_3&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_image src=\u00a0\u00bbhttps:\/\/e-fouche.fr\/wp-content\/uploads\/2026\/08\/LU_Inser_2.jpg\u00a0\u00bb title_text=\u00a0\u00bbLU_Inser_2&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_image src=\u00a0\u00bbhttps:\/\/e-fouche.fr\/wp-content\/uploads\/2026\/08\/inser-331.jpg\u00a0\u00bb title_text=\u00a0\u00bbinser-331&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb-1px|||||\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_image src=\u00a0\u00bbhttps:\/\/e-fouche.fr\/wp-content\/uploads\/2026\/02\/inser-44-scaled.jpg\u00a0\u00bb title_text=\u00a0\u00bbinser-44&Prime; _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_divider _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb color=\u00a0\u00bb#808080&Prime; hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime; custom_margin=\u00a0\u00bb||-15px|||\u00a0\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime; custom_margin=\u00a0\u00bb||9px|||\u00a0\u00bb]<\/p>\n<p>EXISTANT<\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00a0\u00bbhttps:\/\/e-fouche.fr\/wp-content\/uploads\/2026\/08\/IMG_20251216_095452295_HDR.jpg\u00a0\u00bb title_text=\u00a0\u00bbhdr\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb custom_padding=\u00a0\u00bb4px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_image src=\u00a0\u00bbhttps:\/\/e-fouche.fr\/wp-content\/uploads\/2026\/08\/IMG_20251007_150504742_HDR.jpg\u00a0\u00bb title_text=\u00a0\u00bbhdr\u00a0\u00bb force_fullwidth=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.5&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ma\u00eetre d\u2019Ouvrage : Commune de LUSSAC (33670) Contenu de la mission : Extension Salle de DOJO dans le pr\u00e9au ecistant , Yoga et bureau Surface cr\u00e9e : 376m\u00b2\u00a0 Montant des travaux : 376 K\u20ac HT Livraison : Avril 2027 (PRO en cours) Particularit\u00e9 du projet\u00a0 Structure et toiture conserv\u00e9s Construction bas carbone en bois et [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[],"project_tag":[],"class_list":["post-795","project","type-project","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/e-fouche.fr\/index.php\/wp-json\/wp\/v2\/project\/795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-fouche.fr\/index.php\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/e-fouche.fr\/index.php\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/e-fouche.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/e-fouche.fr\/index.php\/wp-json\/wp\/v2\/comments?post=795"}],"version-history":[{"count":7,"href":"https:\/\/e-fouche.fr\/index.php\/wp-json\/wp\/v2\/project\/795\/revisions"}],"predecessor-version":[{"id":980,"href":"https:\/\/e-fouche.fr\/index.php\/wp-json\/wp\/v2\/project\/795\/revisions\/980"}],"wp:attachment":[{"href":"https:\/\/e-fouche.fr\/index.php\/wp-json\/wp\/v2\/media?parent=795"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/e-fouche.fr\/index.php\/wp-json\/wp\/v2\/project_category?post=795"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/e-fouche.fr\/index.php\/wp-json\/wp\/v2\/project_tag?post=795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}